{"id":3,"date":"2024-04-02T21:24:11","date_gmt":"2024-04-02T19:24:11","guid":{"rendered":"https:\/\/gasthof-gruber.de\/Gruber24\/?page_id=3"},"modified":"2024-04-04T00:31:16","modified_gmt":"2024-04-03T22:31:16","slug":"datenschutzerklaerung","status":"publish","type":"page","link":"https:\/\/gasthof-gruber.de\/Gruber24\/datenschutzerklaerung\/","title":{"rendered":"Datenschutzerkl\u00e4rung"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Wer wir sind<\/h2>\n\n\n\n<p>Die Adresse unserer Website ist: http:\/\/gasthof-gruber.de.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Kommentare<\/h2>\n\n\n\n<p>Wenn Besucher Kommentare auf der Website schreiben, sammeln wir die Daten, die im Kommentar-Formular angezeigt werden, au\u00dferdem die IP-Adresse des Besuchers und den User-Agent-String (damit wird der Browser identifiziert), um die Erkennung von Spam zu unterst\u00fctzen.<\/p>\n\n\n\n<p>Aus deiner E-Mail-Adresse kann eine anonymisierte Zeichenfolge erstellt (auch Hash genannt) und dem Gravatar-Dienst \u00fcbergeben werden, um zu pr\u00fcfen, ob du diesen benutzt. Die Datenschutzerkl\u00e4rung des Gravatar-Dienstes findest du hier: https:\/\/automattic.com\/privacy\/. Nachdem dein Kommentar freigegeben wurde, ist dein Profilbild \u00f6ffentlich im Kontext deines Kommentars sichtbar.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Medien<\/h2>\n\n\n\n<p>Wenn du ein registrierter Benutzer bist und Fotos auf diese Website l\u00e4dst, solltest du vermeiden, Fotos mit einem EXIF-GPS-Standort hochzuladen. Besucher dieser Website k\u00f6nnten Fotos, die auf dieser Website gespeichert sind, herunterladen und deren Standort-Informationen extrahieren.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Cookies<\/h2>\n\n\n\n<p>Wenn du einen Kommentar auf unserer Website schreibst, kann das eine Einwilligung sein, deinen Namen, E-Mail-Adresse und Website in Cookies zu speichern. Dies ist eine Komfortfunktion, damit du nicht, wenn du einen weiteren Kommentar schreibst, all diese Daten erneut eingeben musst. Diese Cookies werden ein Jahr lang gespeichert.<\/p>\n\n\n\n<p>Falls du ein Konto hast und dich auf dieser Website anmeldest, werden wir ein tempor\u00e4res Cookie setzen, um festzustellen, ob dein Browser Cookies akzeptiert. Dieses Cookie enth\u00e4lt keine personenbezogenen Daten und wird verworfen, wenn du deinen Browser schlie\u00dft.<\/p>\n\n\n\n<p>Wenn du dich anmeldest, werden wir einige Cookies einrichten, um deine Anmeldeinformationen und Anzeigeoptionen zu speichern. Anmelde-Cookies verfallen nach zwei Tagen und Cookies f\u00fcr die Anzeigeoptionen nach einem Jahr. Falls du bei der Anmeldung \u201eAngemeldet bleiben\u201c ausw\u00e4hlst, wird deine Anmeldung zwei Wochen lang aufrechterhalten. Mit der Abmeldung aus deinem Konto werden die Anmelde-Cookies gel\u00f6scht.<\/p>\n\n\n\n<p>Wenn du einen Artikel bearbeitest oder ver\u00f6ffentlichst, wird ein zus\u00e4tzlicher Cookie in deinem Browser gespeichert. Dieser Cookie enth\u00e4lt keine personenbezogenen Daten und verweist nur auf die Beitrags-ID des Artikels, den du gerade bearbeitet hast. Der Cookie verf\u00e4llt nach einem Tag.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Eingebettete Inhalte von anderen Websites<\/h2>\n\n\n\n<p>Beitr\u00e4ge auf dieser Website k\u00f6nnen eingebettete Inhalte beinhalten (z.\u00a0B. Videos, Bilder, Beitr\u00e4ge etc.). Eingebettete Inhalte von anderen Websites verhalten sich exakt so, als ob der Besucher die andere Website besucht h\u00e4tte.<\/p>\n\n\n\n<p>Diese Websites k\u00f6nnen Daten \u00fcber dich sammeln, Cookies benutzen, zus\u00e4tzliche Tracking-Dienste von Dritten einbetten und deine Interaktion mit diesem eingebetteten Inhalt aufzeichnen, inklusive deiner Interaktion mit dem eingebetteten Inhalt, falls du ein Konto hast und auf dieser Website angemeldet bist.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Mit wem wir deine Daten teilen<\/h2>\n\n\n\n<p>Wenn du eine Zur\u00fccksetzung des Passworts beantragst, wird deine IP-Adresse in der E-Mail zur Zur\u00fccksetzung enthalten sein.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Wie lange wir deine Daten speichern<\/h2>\n\n\n\n<p>Wenn du einen Kommentar schreibst, wird dieser inklusive Metadaten zeitlich unbegrenzt gespeichert. Auf diese Art k\u00f6nnen wir Folgekommentare automatisch erkennen und freigeben, anstatt sie in einer Moderations-Warteschlange festzuhalten.<\/p>\n\n\n\n<p>F\u00fcr Benutzer, die sich auf unserer Website registrieren, speichern wir zus\u00e4tzlich die pers\u00f6nlichen Informationen, die sie in ihren Benutzerprofilen angeben. Alle Benutzer k\u00f6nnen jederzeit ihre pers\u00f6nlichen Informationen einsehen, ver\u00e4ndern oder l\u00f6schen (der Benutzername kann nicht ver\u00e4ndert werden). Administratoren der Website k\u00f6nnen diese Informationen ebenfalls einsehen und ver\u00e4ndern.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Welche Rechte du an deinen Daten hast<\/h2>\n\n\n\n<p>Wenn du ein Konto auf dieser Website besitzt oder Kommentare geschrieben hast, kannst du einen Export deiner personenbezogenen Daten bei uns anfordern, inklusive aller Daten, die du uns mitgeteilt hast. Dar\u00fcber hinaus kannst du die L\u00f6schung aller personenbezogenen Daten, die wir von dir gespeichert haben, anfordern. Dies umfasst nicht die Daten, die wir aufgrund administrativer, rechtlicher oder sicherheitsrelevanter Notwendigkeiten aufbewahren m\u00fcssen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Wohin deine Daten gesendet werden<\/h2>\n\n\n\n<p>Besucher-Kommentare k\u00f6nnten von einem automatisierten Dienst zur Spam-Erkennung untersucht werden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wer wir sind Die Adresse unserer Website ist: http:\/\/gasthof-gruber.de. Kommentare Wenn Besucher Kommentare auf der Website schreiben, sammeln wir die Daten, die im Kommentar-Formular angezeigt werden, au\u00dferdem die IP-Adresse des Besuchers und den User-Agent-String (damit wird der Browser identifiziert), um die Erkennung von Spam zu unterst\u00fctzen. Aus deiner E-Mail-Adresse kann eine anonymisierte Zeichenfolge erstellt (auch &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/gasthof-gruber.de\/Gruber24\/datenschutzerklaerung\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eDatenschutzerkl\u00e4rung\u201c <\/span>weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-3","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gasthof Gruber - Urlaub im Chiemgau - Datenschutz<\/title>\n<meta name=\"description\" content=\"Genie\u00dfen Sie Ihren Urlaub im Chiemgau oder Besuchen sie unser Restaurant - Erholung in bayerischer Tradition\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gasthof-gruber.de\/Gruber24\/datenschutzerklaerung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gasthof Gruber - Urlaub im Chiemgau - Datenschutz\" \/>\n<meta property=\"og:description\" content=\"Genie\u00dfen Sie Ihren Urlaub im Chiemgau oder Besuchen sie unser Restaurant - Erholung in bayerischer Tradition\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gasthof-gruber.de\/Gruber24\/datenschutzerklaerung\/\" \/>\n<meta property=\"og:site_name\" content=\"Gasthof Gruber\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/p\/Gasthof-Gruber-100027918356868\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-03T22:31:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gasthof-gruber.de\/Gruber24\/wp-content\/uploads\/2024\/04\/cropped-kontakt2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gasthof-gruber.de\\\/Gruber24\\\/datenschutzerklaerung\\\/\",\"url\":\"https:\\\/\\\/gasthof-gruber.de\\\/Gruber24\\\/datenschutzerklaerung\\\/\",\"name\":\"Gasthof Gruber - Urlaub im Chiemgau - Datenschutz\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gasthof-gruber.de\\\/Gruber24\\\/#website\"},\"datePublished\":\"2024-04-02T19:24:11+00:00\",\"dateModified\":\"2024-04-03T22:31:16+00:00\",\"description\":\"Genie\u00dfen Sie Ihren Urlaub im Chiemgau oder Besuchen sie unser Restaurant - Erholung in bayerischer Tradition\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gasthof-gruber.de\\\/Gruber24\\\/datenschutzerklaerung\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gasthof-gruber.de\\\/Gruber24\\\/datenschutzerklaerung\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gasthof-gruber.de\\\/Gruber24\\\/datenschutzerklaerung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/gasthof-gruber.de\\\/Gruber24\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Datenschutzerkl\u00e4rung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gasthof-gruber.de\\\/Gruber24\\\/#website\",\"url\":\"https:\\\/\\\/gasthof-gruber.de\\\/Gruber24\\\/\",\"name\":\"Gasthof Gruber\",\"description\":\"Urlaub im Chiemgau\",\"publisher\":{\"@id\":\"https:\\\/\\\/gasthof-gruber.de\\\/Gruber24\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gasthof-gruber.de\\\/Gruber24\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gasthof-gruber.de\\\/Gruber24\\\/#organization\",\"name\":\"Gasthof Gruber\",\"url\":\"https:\\\/\\\/gasthof-gruber.de\\\/Gruber24\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/gasthof-gruber.de\\\/Gruber24\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gasthof-gruber.de\\\/Gruber24\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/logo-Gruber-schwarz.png\",\"contentUrl\":\"https:\\\/\\\/gasthof-gruber.de\\\/Gruber24\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/logo-Gruber-schwarz.png\",\"width\":2031,\"height\":535,\"caption\":\"Gasthof Gruber\"},\"image\":{\"@id\":\"https:\\\/\\\/gasthof-gruber.de\\\/Gruber24\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/p\\\/Gasthof-Gruber-100027918356868\\\/\",\"https:\\\/\\\/www.instagram.com\\\/gasthofgruber\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gasthof Gruber - Urlaub im Chiemgau - Datenschutz","description":"Genie\u00dfen Sie Ihren Urlaub im Chiemgau oder Besuchen sie unser Restaurant - Erholung in bayerischer Tradition","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gasthof-gruber.de\/Gruber24\/datenschutzerklaerung\/","og_locale":"de_DE","og_type":"article","og_title":"Gasthof Gruber - Urlaub im Chiemgau - Datenschutz","og_description":"Genie\u00dfen Sie Ihren Urlaub im Chiemgau oder Besuchen sie unser Restaurant - Erholung in bayerischer Tradition","og_url":"https:\/\/gasthof-gruber.de\/Gruber24\/datenschutzerklaerung\/","og_site_name":"Gasthof Gruber","article_publisher":"https:\/\/www.facebook.com\/p\/Gasthof-Gruber-100027918356868\/","article_modified_time":"2024-04-03T22:31:16+00:00","og_image":[{"width":2000,"height":1200,"url":"https:\/\/gasthof-gruber.de\/Gruber24\/wp-content\/uploads\/2024\/04\/cropped-kontakt2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/gasthof-gruber.de\/Gruber24\/datenschutzerklaerung\/","url":"https:\/\/gasthof-gruber.de\/Gruber24\/datenschutzerklaerung\/","name":"Gasthof Gruber - Urlaub im Chiemgau - Datenschutz","isPartOf":{"@id":"https:\/\/gasthof-gruber.de\/Gruber24\/#website"},"datePublished":"2024-04-02T19:24:11+00:00","dateModified":"2024-04-03T22:31:16+00:00","description":"Genie\u00dfen Sie Ihren Urlaub im Chiemgau oder Besuchen sie unser Restaurant - Erholung in bayerischer Tradition","breadcrumb":{"@id":"https:\/\/gasthof-gruber.de\/Gruber24\/datenschutzerklaerung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gasthof-gruber.de\/Gruber24\/datenschutzerklaerung\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/gasthof-gruber.de\/Gruber24\/datenschutzerklaerung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/gasthof-gruber.de\/Gruber24\/"},{"@type":"ListItem","position":2,"name":"Datenschutzerkl\u00e4rung"}]},{"@type":"WebSite","@id":"https:\/\/gasthof-gruber.de\/Gruber24\/#website","url":"https:\/\/gasthof-gruber.de\/Gruber24\/","name":"Gasthof Gruber","description":"Urlaub im Chiemgau","publisher":{"@id":"https:\/\/gasthof-gruber.de\/Gruber24\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gasthof-gruber.de\/Gruber24\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/gasthof-gruber.de\/Gruber24\/#organization","name":"Gasthof Gruber","url":"https:\/\/gasthof-gruber.de\/Gruber24\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/gasthof-gruber.de\/Gruber24\/#\/schema\/logo\/image\/","url":"https:\/\/gasthof-gruber.de\/Gruber24\/wp-content\/uploads\/2024\/04\/logo-Gruber-schwarz.png","contentUrl":"https:\/\/gasthof-gruber.de\/Gruber24\/wp-content\/uploads\/2024\/04\/logo-Gruber-schwarz.png","width":2031,"height":535,"caption":"Gasthof Gruber"},"image":{"@id":"https:\/\/gasthof-gruber.de\/Gruber24\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/p\/Gasthof-Gruber-100027918356868\/","https:\/\/www.instagram.com\/gasthofgruber\/"]}]}},"_links":{"self":[{"href":"https:\/\/gasthof-gruber.de\/Gruber24\/wp-json\/wp\/v2\/pages\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gasthof-gruber.de\/Gruber24\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/gasthof-gruber.de\/Gruber24\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/gasthof-gruber.de\/Gruber24\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gasthof-gruber.de\/Gruber24\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":1,"href":"https:\/\/gasthof-gruber.de\/Gruber24\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"predecessor-version":[{"id":139,"href":"https:\/\/gasthof-gruber.de\/Gruber24\/wp-json\/wp\/v2\/pages\/3\/revisions\/139"}],"wp:attachment":[{"href":"https:\/\/gasthof-gruber.de\/Gruber24\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}