{"id":207,"date":"2024-04-04T09:58:26","date_gmt":"2024-04-04T07:58:26","guid":{"rendered":"https:\/\/gasthof-gruber.de\/Gruber24\/?page_id=207"},"modified":"2024-04-04T09:58:27","modified_gmt":"2024-04-04T07:58:27","slug":"impressum","status":"publish","type":"page","link":"https:\/\/gasthof-gruber.de\/Gruber24\/impressum\/","title":{"rendered":"Impressum"},"content":{"rendered":"\n<h1 class=\"wp-block-heading\">Impressum<\/h1>\n\n\n\n<p>Angaben gem\u00e4\u00df \u00a7 5 TMG<\/p>\n\n\n\n<p>Gasthof Gruber<br>Hauptstra\u00dfe 27<br>83413 Fridolfing<br><\/p>\n\n\n\n<p><strong>Vertreten durch:<\/strong><br>Michael Gruber<br><\/p>\n\n\n\n<p><strong>Kontakt:<\/strong><br>Telefon: 08684-236<br>E-Mail: <a href=\"mailto:Gasthof_Gruber@t-online.de\">Gasthof_Gruber@t-online.de<\/a><\/p>\n\n\n\n<p><strong>Umsatzsteuer-ID:<\/strong><br>Umsatzsteuer-Identifikationsnummer gem\u00e4\u00df \u00a727a Umsatzsteuergesetz: DE348701666<br><br><\/p>\n\n\n\n<p><strong>Haftungsausschluss:<\/strong><br><br><strong>Haftung f\u00fcr Inhalte<\/strong><br><br>Die Inhalte unserer Seiten wurden mit gr\u00f6\u00dfter Sorgfalt erstellt. F\u00fcr die Richtigkeit, Vollst\u00e4ndigkeit und Aktualit\u00e4t der Inhalte k\u00f6nnen wir jedoch keine Gew\u00e4hr \u00fcbernehmen. Als Diensteanbieter sind wir gem\u00e4\u00df \u00a7 7 Abs.1 TMG f\u00fcr eigene Inhalte auf diesen Seiten nach den allgemeinen Gesetzen verantwortlich. Nach \u00a7\u00a7 8 bis 10 TMG sind wir als Diensteanbieter jedoch nicht verpflichtet, \u00fcbermittelte oder gespeicherte fremde Informationen zu \u00fcberwachen oder nach Umst\u00e4nden zu forschen, die auf eine rechtswidrige T\u00e4tigkeit hinweisen. Verpflichtungen zur Entfernung oder Sperrung der Nutzung von Informationen nach den allgemeinen Gesetzen bleiben hiervon unber\u00fchrt. Eine diesbez\u00fcgliche Haftung ist jedoch erst ab dem Zeitpunkt der Kenntnis einer konkreten Rechtsverletzung m\u00f6glich. Bei Bekanntwerden von entsprechenden Rechtsverletzungen werden wir diese Inhalte umgehend entfernen.<br><br><strong>Haftung f\u00fcr Links<\/strong><br><br>Unser Angebot enth\u00e4lt Links zu externen Webseiten Dritter, auf deren Inhalte wir keinen Einfluss haben. Deshalb k\u00f6nnen wir f\u00fcr diese fremden Inhalte auch keine Gew\u00e4hr \u00fcbernehmen. F\u00fcr die Inhalte der verlinkten Seiten ist stets der jeweilige Anbieter oder Betreiber der Seiten verantwortlich. Die verlinkten Seiten wurden zum Zeitpunkt der Verlinkung auf m\u00f6gliche Rechtsverst\u00f6\u00dfe \u00fcberpr\u00fcft. Rechtswidrige Inhalte waren zum Zeitpunkt der Verlinkung nicht erkennbar. Eine permanente inhaltliche Kontrolle der verlinkten Seiten ist jedoch ohne konkrete Anhaltspunkte einer Rechtsverletzung nicht zumutbar. Bei Bekanntwerden von Rechtsverletzungen werden wir derartige Links umgehend entfernen.<br><br><strong>Urheberrecht<\/strong><br><br>Die durch die Seitenbetreiber erstellten Inhalte und Werke auf diesen Seiten unterliegen dem deutschen Urheberrecht. Die Vervielf\u00e4ltigung, Bearbeitung, Verbreitung und jede Art der Verwertung au\u00dferhalb der Grenzen des Urheberrechtes bed\u00fcrfen der schriftlichen Zustimmung des jeweiligen Autors bzw. Erstellers. Downloads und Kopien dieser Seite sind nur f\u00fcr den privaten, nicht kommerziellen Gebrauch gestattet. Soweit die Inhalte auf dieser Seite nicht vom Betreiber erstellt wurden, werden die Urheberrechte Dritter beachtet. Insbesondere werden Inhalte Dritter als solche gekennzeichnet. Sollten Sie trotzdem auf eine Urheberrechtsverletzung aufmerksam werden, bitten wir um einen entsprechenden Hinweis. Bei Bekanntwerden von Rechtsverletzungen werden wir derartige Inhalte umgehend entfernen.<br><br><strong>Datenschutz<\/strong><br><br>Die Nutzung unserer Webseite ist in der Regel ohne Angabe personenbezogener Daten m\u00f6glich. Soweit auf unseren Seiten personenbezogene Daten (beispielsweise Name, Anschrift oder eMail-Adressen) erhoben werden, erfolgt dies, soweit m\u00f6glich, stets auf freiwilliger Basis. Diese Daten werden ohne Ihre ausdr\u00fcckliche Zustimmung nicht an Dritte weitergegeben.<br>Wir weisen darauf hin, dass die Daten\u00fcbertragung im Internet (z.B. bei der Kommunikation per E-Mail) Sicherheitsl\u00fccken aufweisen kann. Ein l\u00fcckenloser Schutz der Daten vor dem Zugriff durch Dritte ist nicht m\u00f6glich.<br>Der Nutzung von im Rahmen der Impressumspflicht ver\u00f6ffentlichten Kontaktdaten durch Dritte zur \u00dcbersendung von nicht ausdr\u00fccklich angeforderter Werbung und Informationsmaterialien wird hiermit ausdr\u00fccklich widersprochen. Die Betreiber der Seiten behalten sich ausdr\u00fccklich rechtliche Schritte im Falle der unverlangten Zusendung von Werbeinformationen, etwa durch Spam-Mails, vor.<br><br><br><strong>Google Analytics<\/strong><br><br>Diese Website benutzt Google Analytics, einen Webanalysedienst der Google Inc. (&#8220;Google&#8220;). Google Analytics verwendet sog. &#8220;Cookies&#8220;, Textdateien, die auf Ihrem Computer gespeichert werden und die eine Analyse der Benutzung der Website durch Sie erm\u00f6glicht. Die durch den Cookie erzeugten Informationen \u00fcber Ihre Benutzung dieser Website (einschlie\u00dflich Ihrer IP-Adresse) wird an einen Server von Google in den USA \u00fcbertragen und dort gespeichert. Google wird diese Informationen benutzen, um Ihre Nutzung der Website auszuwerten, um Reports \u00fcber die Websiteaktivit\u00e4ten f\u00fcr die Websitebetreiber zusammenzustellen und um weitere mit der Websitenutzung und der Internetnutzung verbundene Dienstleistungen zu erbringen. Auch wird Google diese Informationen gegebenenfalls an Dritte \u00fcbertragen, sofern dies gesetzlich vorgeschrieben oder soweit Dritte diese Daten im Auftrag von Google verarbeiten. Google wird in keinem Fall Ihre IP-Adresse mit anderen Daten der Google in Verbindung bringen. Sie k\u00f6nnen die Installation der Cookies durch eine entsprechende Einstellung Ihrer Browser Software verhindern; wir weisen Sie jedoch darauf hin, dass Sie in diesem Fall gegebenenfalls nicht s\u00e4mtliche Funktionen dieser Website voll umf\u00e4nglich nutzen k\u00f6nnen. Durch die Nutzung dieser Website erkl\u00e4ren Sie sich mit der Bearbeitung der \u00fcber Sie erhobenen Daten durch Google in der zuvor beschriebenen Art und Weise und zu dem zuvor benannten Zweck einverstanden.<br><br><strong>Google AdSense<\/strong><br><br>Diese Website benutzt Google Adsense, einen Webanzeigendienst der Google Inc., USA (&#8220;Google&#8220;). Google Adsense verwendet sog. &#8220;Cookies&#8220; (Textdateien), die auf Ihrem Computer gespeichert werden und die eine Analyse der Benutzung der Website durch Sie erm\u00f6glicht. Google Adsense verwendet auch sog. &#8220;Web Beacons&#8220; (kleine unsichtbare Grafiken) zur Sammlung von Informationen. Durch die Verwendung des Web Beacons k\u00f6nnen einfache Aktionen wie der Besucherverkehr auf der Webseite aufgezeichnet und gesammelt werden. Die durch den Cookie und\/oder Web Beacon erzeugten Informationen \u00fcber Ihre Benutzung dieser Website (einschlie\u00dflich Ihrer IP-Adresse) werden an einen Server von Google in den USA \u00fcbertragen und dort gespeichert. Google wird diese Informationen benutzen, um Ihre Nutzung der Website im Hinblick auf die Anzeigen auszuwerten, um Reports \u00fcber die Websiteaktivit\u00e4ten und Anzeigen f\u00fcr die Websitebetreiber zusammenzustellen und um weitere mit der Websitenutzung und der Internetnutzung verbundene Dienstleistungen zu erbringen. Auch wird Google diese Informationen gegebenenfalls an Dritte \u00fcbertragen, sofern dies gesetzlich vorgeschrieben oder soweit Dritte diese Daten im Auftrag von Google verarbeiten. Google wird in keinem Fall Ihre IP-Adresse mit anderen Daten der Google in Verbindung bringen. Das Speichern von Cookies auf Ihrer Festplatte und die Anzeige von Web Beacons k\u00f6nnen Sie verhindern, indem Sie in Ihren Browser-Einstellungen &#8220;keine Cookies akzeptieren&#8220; w\u00e4hlen (Im MS Internet-Explorer unter &#8220;Extras &gt; Internetoptionen &gt; Datenschutz &gt; Einstellung&#8220;; im Firefox unter &#8220;Extras &gt; Einstellungen &gt; Datenschutz &gt; Cookies&#8220;); wir weisen Sie jedoch darauf hin, dass Sie in diesem Fall gegebenenfalls nicht s\u00e4mtliche Funktionen dieser Website voll umf\u00e4nglich nutzen k\u00f6nnen. Durch die Nutzung dieser Website erkl\u00e4ren Sie sich mit der Bearbeitung der \u00fcber Sie erhobenen Daten durch Google in der zuvor beschriebenen Art und Weise und zu dem zuvor benannten Zweck einverstanden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Impressum Angaben gem\u00e4\u00df \u00a7 5 TMG Gasthof GruberHauptstra\u00dfe 2783413 Fridolfing Vertreten durch:Michael Gruber Kontakt:Telefon: 08684-236E-Mail: Gasthof_Gruber@t-online.de Umsatzsteuer-ID:Umsatzsteuer-Identifikationsnummer gem\u00e4\u00df \u00a727a Umsatzsteuergesetz: DE348701666 Haftungsausschluss: Haftung f\u00fcr Inhalte Die Inhalte unserer Seiten wurden mit gr\u00f6\u00dfter Sorgfalt erstellt. F\u00fcr die Richtigkeit, Vollst\u00e4ndigkeit und Aktualit\u00e4t der Inhalte k\u00f6nnen wir jedoch keine Gew\u00e4hr \u00fcbernehmen. Als Diensteanbieter sind wir gem\u00e4\u00df \u00a7 7 &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/gasthof-gruber.de\/Gruber24\/impressum\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eImpressum\u201c <\/span>weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-207","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Impressum - Gasthof Gruber<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gasthof-gruber.de\/Gruber24\/impressum\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Impressum - Gasthof Gruber\" \/>\n<meta property=\"og:description\" content=\"Impressum Angaben gem\u00e4\u00df \u00a7 5 TMG Gasthof GruberHauptstra\u00dfe 2783413 Fridolfing Vertreten durch:Michael Gruber Kontakt:Telefon: 08684-236E-Mail: Gasthof_Gruber@t-online.de Umsatzsteuer-ID:Umsatzsteuer-Identifikationsnummer gem\u00e4\u00df \u00a727a Umsatzsteuergesetz: DE348701666 Haftungsausschluss: Haftung f\u00fcr Inhalte Die Inhalte unserer Seiten wurden mit gr\u00f6\u00dfter Sorgfalt erstellt. F\u00fcr die Richtigkeit, Vollst\u00e4ndigkeit und Aktualit\u00e4t der Inhalte k\u00f6nnen wir jedoch keine Gew\u00e4hr \u00fcbernehmen. Als Diensteanbieter sind wir gem\u00e4\u00df \u00a7 7 &hellip; \u201eImpressum\u201c weiterlesen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gasthof-gruber.de\/Gruber24\/impressum\/\" \/>\n<meta property=\"og:site_name\" content=\"Gasthof Gruber\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/p\/Gasthof-Gruber-100027918356868\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-04T07:58:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gasthof-gruber.de\/Gruber24\/wp-content\/uploads\/2024\/04\/cropped-kontakt2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gasthof-gruber.de\\\/Gruber24\\\/impressum\\\/\",\"url\":\"https:\\\/\\\/gasthof-gruber.de\\\/Gruber24\\\/impressum\\\/\",\"name\":\"Impressum - Gasthof Gruber\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gasthof-gruber.de\\\/Gruber24\\\/#website\"},\"datePublished\":\"2024-04-04T07:58:26+00:00\",\"dateModified\":\"2024-04-04T07:58:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gasthof-gruber.de\\\/Gruber24\\\/impressum\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gasthof-gruber.de\\\/Gruber24\\\/impressum\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gasthof-gruber.de\\\/Gruber24\\\/impressum\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/gasthof-gruber.de\\\/Gruber24\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Impressum\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gasthof-gruber.de\\\/Gruber24\\\/#website\",\"url\":\"https:\\\/\\\/gasthof-gruber.de\\\/Gruber24\\\/\",\"name\":\"Gasthof Gruber\",\"description\":\"Urlaub im Chiemgau\",\"publisher\":{\"@id\":\"https:\\\/\\\/gasthof-gruber.de\\\/Gruber24\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gasthof-gruber.de\\\/Gruber24\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gasthof-gruber.de\\\/Gruber24\\\/#organization\",\"name\":\"Gasthof Gruber\",\"url\":\"https:\\\/\\\/gasthof-gruber.de\\\/Gruber24\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/gasthof-gruber.de\\\/Gruber24\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gasthof-gruber.de\\\/Gruber24\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/logo-Gruber-schwarz.png\",\"contentUrl\":\"https:\\\/\\\/gasthof-gruber.de\\\/Gruber24\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/logo-Gruber-schwarz.png\",\"width\":2031,\"height\":535,\"caption\":\"Gasthof Gruber\"},\"image\":{\"@id\":\"https:\\\/\\\/gasthof-gruber.de\\\/Gruber24\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/p\\\/Gasthof-Gruber-100027918356868\\\/\",\"https:\\\/\\\/www.instagram.com\\\/gasthofgruber\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Impressum - Gasthof Gruber","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gasthof-gruber.de\/Gruber24\/impressum\/","og_locale":"de_DE","og_type":"article","og_title":"Impressum - Gasthof Gruber","og_description":"Impressum Angaben gem\u00e4\u00df \u00a7 5 TMG Gasthof GruberHauptstra\u00dfe 2783413 Fridolfing Vertreten durch:Michael Gruber Kontakt:Telefon: 08684-236E-Mail: Gasthof_Gruber@t-online.de Umsatzsteuer-ID:Umsatzsteuer-Identifikationsnummer gem\u00e4\u00df \u00a727a Umsatzsteuergesetz: DE348701666 Haftungsausschluss: Haftung f\u00fcr Inhalte Die Inhalte unserer Seiten wurden mit gr\u00f6\u00dfter Sorgfalt erstellt. F\u00fcr die Richtigkeit, Vollst\u00e4ndigkeit und Aktualit\u00e4t der Inhalte k\u00f6nnen wir jedoch keine Gew\u00e4hr \u00fcbernehmen. Als Diensteanbieter sind wir gem\u00e4\u00df \u00a7 7 &hellip; \u201eImpressum\u201c weiterlesen","og_url":"https:\/\/gasthof-gruber.de\/Gruber24\/impressum\/","og_site_name":"Gasthof Gruber","article_publisher":"https:\/\/www.facebook.com\/p\/Gasthof-Gruber-100027918356868\/","article_modified_time":"2024-04-04T07:58:27+00:00","og_image":[{"width":2000,"height":1200,"url":"https:\/\/gasthof-gruber.de\/Gruber24\/wp-content\/uploads\/2024\/04\/cropped-kontakt2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/gasthof-gruber.de\/Gruber24\/impressum\/","url":"https:\/\/gasthof-gruber.de\/Gruber24\/impressum\/","name":"Impressum - Gasthof Gruber","isPartOf":{"@id":"https:\/\/gasthof-gruber.de\/Gruber24\/#website"},"datePublished":"2024-04-04T07:58:26+00:00","dateModified":"2024-04-04T07:58:27+00:00","breadcrumb":{"@id":"https:\/\/gasthof-gruber.de\/Gruber24\/impressum\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gasthof-gruber.de\/Gruber24\/impressum\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/gasthof-gruber.de\/Gruber24\/impressum\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/gasthof-gruber.de\/Gruber24\/"},{"@type":"ListItem","position":2,"name":"Impressum"}]},{"@type":"WebSite","@id":"https:\/\/gasthof-gruber.de\/Gruber24\/#website","url":"https:\/\/gasthof-gruber.de\/Gruber24\/","name":"Gasthof Gruber","description":"Urlaub im Chiemgau","publisher":{"@id":"https:\/\/gasthof-gruber.de\/Gruber24\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gasthof-gruber.de\/Gruber24\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/gasthof-gruber.de\/Gruber24\/#organization","name":"Gasthof Gruber","url":"https:\/\/gasthof-gruber.de\/Gruber24\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/gasthof-gruber.de\/Gruber24\/#\/schema\/logo\/image\/","url":"https:\/\/gasthof-gruber.de\/Gruber24\/wp-content\/uploads\/2024\/04\/logo-Gruber-schwarz.png","contentUrl":"https:\/\/gasthof-gruber.de\/Gruber24\/wp-content\/uploads\/2024\/04\/logo-Gruber-schwarz.png","width":2031,"height":535,"caption":"Gasthof Gruber"},"image":{"@id":"https:\/\/gasthof-gruber.de\/Gruber24\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/p\/Gasthof-Gruber-100027918356868\/","https:\/\/www.instagram.com\/gasthofgruber\/"]}]}},"_links":{"self":[{"href":"https:\/\/gasthof-gruber.de\/Gruber24\/wp-json\/wp\/v2\/pages\/207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gasthof-gruber.de\/Gruber24\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/gasthof-gruber.de\/Gruber24\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/gasthof-gruber.de\/Gruber24\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gasthof-gruber.de\/Gruber24\/wp-json\/wp\/v2\/comments?post=207"}],"version-history":[{"count":1,"href":"https:\/\/gasthof-gruber.de\/Gruber24\/wp-json\/wp\/v2\/pages\/207\/revisions"}],"predecessor-version":[{"id":208,"href":"https:\/\/gasthof-gruber.de\/Gruber24\/wp-json\/wp\/v2\/pages\/207\/revisions\/208"}],"wp:attachment":[{"href":"https:\/\/gasthof-gruber.de\/Gruber24\/wp-json\/wp\/v2\/media?parent=207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}